{"id":286,"date":"2022-01-22T11:02:08","date_gmt":"2022-01-22T10:02:08","guid":{"rendered":"https:\/\/drvereshzoltan.hu\/?page_id=286"},"modified":"2025-03-31T17:40:52","modified_gmt":"2025-03-31T16:40:52","slug":"rolam","status":"publish","type":"page","link":"https:\/\/drvereshzoltan.hu\/hu_hu\/rolam\/","title":{"rendered":"R\u00f3lam"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"286\" class=\"elementor elementor-286\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a1d4fd7 elementor-section-stretched elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"7a1d4fd7\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5d8a72e4\" data-id=\"5d8a72e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-2a115f0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a115f0a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5039e407\" data-id=\"5039e407\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e43db2 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"9e43db2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Dr. Veresh Zolt\u00e1n PhD<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-535c2a63 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"535c2a63\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Sz\u00fcl\u00e9sz-n\u0151gy\u00f3gy\u00e1sz f\u0151orvos, endokrinol\u00f3gia \u00e9s anyagcserebetegs\u00e9gek szakorvosa, klinikai immunol\u00f3gus szakorvos<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2bccfa9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2bccfa9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-801b0f8\" data-id=\"801b0f8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4caa7d elementor-widget elementor-widget-heading\" data-id=\"d4caa7d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><i>\"Fontosnak tartom az \u0151szintes\u00e9get \u00e9s a bizalmat orvos \u00e9s p\u00e1ciense  k\u00f6z\u00f6tt. Minden megold\u00e1shoz figyelem, t\u00fcrelem \u00e9s odaad\u00e1s sz\u00fcks\u00e9ges.\"<\/i><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5eafdb67 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"5eafdb67\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-670a9365\" data-id=\"670a9365\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-6f01f58b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f01f58b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-651897ce\" data-id=\"651897ce\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9340553 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"9340553\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"687\" height=\"1024\" src=\"https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Dr.-Veresh-Zoltan-687x1024.jpg\" class=\"attachment-large size-large wp-image-371\" alt=\"\" srcset=\"https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Dr.-Veresh-Zoltan-687x1024.jpg 687w, https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Dr.-Veresh-Zoltan-201x300.jpg 201w, https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Dr.-Veresh-Zoltan-768x1144.jpg 768w, https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Dr.-Veresh-Zoltan-1031x1536.jpg 1031w, https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Dr.-Veresh-Zoltan-1375x2048.jpg 1375w, https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Dr.-Veresh-Zoltan-scaled.jpg 1718w\" sizes=\"auto, (max-width: 687px) 100vw, 687px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b98ab32 elementor-align-justify elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"4b98ab32\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/drveresh.booked4.us\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Id\u0151pontfoglal\u00e1s<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59a531ed\" data-id=\"59a531ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d2f776e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d2f776e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1a7d7b92\" data-id=\"1a7d7b92\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d4e87d6 elementor-widget elementor-widget-text-editor\" data-id=\"d4e87d6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45376a8 elementor-widget elementor-widget-text-editor\" data-id=\"45376a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p data-pm-slice=\"1 1 []\">1982-ben sz\u00fclettem Beregsz\u00e1szban. K\u00f6z\u00e9piskolai tanulm\u00e1nyaimat a Beregsz\u00e1szi Bethlen G\u00e1bor Magyar Gimn\u00e1ziumban v\u00e9geztem.<\/p><p>2000-ben felv\u00e9telt nyertem a Semmelweis Egyetem \u00c1ltal\u00e1nos Orvostudom\u00e1nyi Kar\u00e1ra, ahol 2006-ban summa cum laude min\u0151s\u00edt\u00e9ssel szereztem meg orvosi diplom\u00e1mat. Ezt k\u00f6vet\u0151en a Semmelweis Egyetem Doktori Iskol\u00e1j\u00e1ban folytattam doktori tanulm\u00e1nyaimat, \u00e9s egy \u00e9vet a New York Medical College-ban is elt\u00f6lt\u00f6ttem. 2011-ben summa cum laude min\u0151s\u00edt\u00e9ssel v\u00e9dtem meg doktori disszert\u00e1ci\u00f3mat.<\/p><p>A sz\u00fcl\u00e9szet-n\u0151gy\u00f3gy\u00e1szat ter\u00fclete mindig is k\u00fcl\u00f6n\u00f6sen \u00e9rdekelt, ez\u00e9rt 2009-t\u0151l rezidensk\u00e9nt, majd 2011 \u00e9s 2017 k\u00f6z\u00f6tt egyetemi tan\u00e1rseg\u00e9dk\u00e9nt dolgoztam a Semmelweis Egyetem I. sz. Sz\u00fcl\u00e9szeti \u00e9s N\u0151gy\u00f3gy\u00e1szati Klinik\u00e1j\u00e1n. 2014-ben sz\u00fcl\u00e9szet-n\u0151gy\u00f3gy\u00e1szatb\u00f3l sikeresen szakvizsg\u00e1t tettem, majd a Budapesti Szent Margit K\u00f3rh\u00e1z Sz\u00fcl\u00e9szet-n\u0151gy\u00f3gy\u00e1szati Oszt\u00e1ly\u00e1ra ker\u00fcltem, ahol jelenleg oszt\u00e1lyvezet\u0151-helyettes f\u0151orvosk\u00e9nt \u00e9s a n\u0151gy\u00f3gy\u00e1szati r\u00e9szleg vezet\u0151jek\u00e9nt dolgozom.<\/p><p>A szakmai \u00e9rdekl\u0151d\u00e9sem k\u00f6z\u00e9ppontj\u00e1ban mindig is a magas kock\u00e1zat\u00fa v\u00e1rand\u00f3sok gondoz\u00e1sa \u00e9s a medd\u0151s\u00e9g kezel\u00e9se \u00e1llt. Ezen k\u00edv\u00fcl kiemelten foglalkozom a n\u0151gy\u00f3gy\u00e1szati betegs\u00e9gekkel, k\u00fcl\u00f6n\u00f6sen az endometri\u00f3zis, a m\u00e9h myom\u00e1s elv\u00e1ltoz\u00e1sai, a policiszt\u00e1s ov\u00e1rium szindr\u00f3ma (PCOS) \u00e9s a hormon\u00e1lis egyens\u00falyhi\u00e1ny okozta probl\u00e9m\u00e1k diagnosztik\u00e1j\u00e1val \u00e9s kezel\u00e9s\u00e9vel.<\/p><p>Ennek kapcs\u00e1n 2020-ban klinikai immunol\u00f3gi\u00e1b\u00f3l \u00e9s allergol\u00f3gi\u00e1b\u00f3l szakvizsg\u00e1t tettem, mivel sok esetben immunol\u00f3giai t\u00e9nyez\u0151k \u00e1llnak ezeknek a probl\u00e9m\u00e1knak a h\u00e1tter\u00e9ben. Ezt a tud\u00e1somat tov\u00e1bb b\u0151v\u00edtve 2022-ben megkezdtem endokrinol\u00f3giai szakk\u00e9pz\u00e9semet, amelyet 2025-ben sikeresen befejeztem, \u00e9s endokrinol\u00f3gi\u00e1b\u00f3l is szakvizsg\u00e1t szereztem. Az endokrinol\u00f3gia ter\u00fclet\u00e9n k\u00fcl\u00f6n\u00f6sen a n\u0151i hormon\u00e1lis elt\u00e9r\u00e9sek, a pajzsmirigybetegs\u00e9gek, a mell\u00e9kvese \u00e9s a petef\u00e9szek m\u0171k\u00f6d\u00e9si zavarai, valamint a medd\u0151s\u00e9ggel \u00f6sszef\u00fcgg\u0151 endokrin probl\u00e9m\u00e1k \u00e9rdekelnek. Munk\u00e1m sor\u00e1n a hormon\u00e1lis egyens\u00faly helyre\u00e1ll\u00edt\u00e1s\u00e1ra t\u00f6rekszem, hogy ezzel is seg\u00edtsem p\u00e1cienseim eg\u00e9szs\u00e9g\u00e9t \u00e9s \u00e9letmin\u0151s\u00e9g\u00e9t.<\/p><p>Mindennapi munk\u00e1m sor\u00e1n arra t\u00f6rekszem, hogy a megszerzett tud\u00e1st \u00e9s tapasztalatot a lehet\u0151 legjobban a p\u00e1cienseim jav\u00e1ra ford\u00edtsam.<\/p><p>Fels\u0151fok\u00fa \u201eC\u201d t\u00edpus\u00fa ukr\u00e1n, k\u00f6z\u00e9pfok\u00fa \u201eC\u201d t\u00edpus\u00fa orosz \u00e9s k\u00f6z\u00e9pfok\u00fa \u201eC\u201d t\u00edpus\u00fa angol nyelvvizsg\u00e1val rendelkezem.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c2e27bd elementor-icon-list--layout-inline elementor-list-item-link-full_width elementor-invisible elementor-widget elementor-widget-icon-list\" data-id=\"1c2e27bd\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/drvereshzoltan.hu\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-phone-square\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+36-20-595-6665<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e716faa elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e716faa\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2ec5222\" data-id=\"2ec5222\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f1d740 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f1d740\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-8b442b3\" data-id=\"8b442b3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c6b064 elementor-widget elementor-widget-heading\" data-id=\"3c6b064\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00f3lam \u00edrt\u00e1k<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-68adbfef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68adbfef\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-68e5d040 elementor-invisible\" data-id=\"68e5d040\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d60afc1 elementor-widget elementor-widget-testimonial\" data-id=\"5d60afc1\" data-element_type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.15.0 - 20-08-2023 *\/\n.elementor-testimonial-wrapper{overflow:hidden;text-align:center}.elementor-testimonial-wrapper .elementor-testimonial-content{font-size:1.3em;margin-bottom:20px}.elementor-testimonial-wrapper .elementor-testimonial-name{line-height:1.5;display:block}.elementor-testimonial-wrapper .elementor-testimonial-job{font-size:.85em;display:block}.elementor-testimonial-wrapper .elementor-testimonial-meta{width:100%;line-height:1}.elementor-testimonial-wrapper .elementor-testimonial-meta-inner{display:inline-block}.elementor-testimonial-wrapper .elementor-testimonial-meta .elementor-testimonial-details,.elementor-testimonial-wrapper .elementor-testimonial-meta .elementor-testimonial-image{display:table-cell;vertical-align:middle}.elementor-testimonial-wrapper .elementor-testimonial-meta .elementor-testimonial-image img{width:60px;height:60px;border-radius:50%;-o-object-fit:cover;object-fit:cover;max-width:none}.elementor-testimonial-wrapper .elementor-testimonial-meta.elementor-testimonial-image-position-aside .elementor-testimonial-image{padding-right:15px}.elementor-testimonial-wrapper .elementor-testimonial-meta.elementor-testimonial-image-position-aside .elementor-testimonial-details{text-align:left}.elementor-testimonial-wrapper .elementor-testimonial-meta.elementor-testimonial-image-position-top .elementor-testimonial-details,.elementor-testimonial-wrapper .elementor-testimonial-meta.elementor-testimonial-image-position-top .elementor-testimonial-image{display:block}.elementor-testimonial-wrapper .elementor-testimonial-meta.elementor-testimonial-image-position-top .elementor-testimonial-image{margin-bottom:20px}<\/style>\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><span dir=\"auto\">\"A Legjobb Orvos \u00c9n N\u00e1la sz\u00fcltem 5\u00e9vv ezel\u00f6tt \u00e9s a legjobb kezekben voltam\n csak aj\u00e1nlani tudom,kedves meg\u00e9rt\u0151 \u00e9s a legnagyobb szivvel l\u00e9lekkel \nv\u00e9gzi a munk\u00e1j\u00e1t<\/span>\"<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/67313955_2534370246623629_1180729188760420352_n-e1643059305943.jpg\" class=\"attachment-full size-full wp-image-979\" alt=\"\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Szilva D. P. <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">P\u00e1ciens<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-577ecd2\" data-id=\"577ecd2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-17989a96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"17989a96\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-39b6ebb4 elementor-invisible\" data-id=\"39b6ebb4\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-25f78d2f elementor-widget elementor-widget-testimonial\" data-id=\"25f78d2f\" data-element_type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\"><span dir=\"auto\">V\u00e9gre  egy orvos, aki megvizsg\u00e1lt rendesen, \u00e9s elmondott mindent pontr\u00f3l pontra! Nagyon kedves \u00e9s a szakm\u00e1j\u00e1t kiv\u00e1l\u00f3an v\u00e9gz\u0151 orvos! Csak \naj\u00e1nlan\u00e1m mindenkinek! Nekem is aj\u00e1nlott\u00e1k \u00e9s nem b\u00e1ntam meg, hogy \u0151t \nv\u00e1lasztottam! <span><img loading=\"lazy\" decoding=\"async\" alt=\"\ud83d\ude42\" src=\"https:\/\/static.xx.fbcdn.net\/images\/emoji.php\/v9\/ta5\/1.5\/16\/1f642.png\" width=\"16\" height=\"16\"><\/span><\/span><\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"190\" height=\"190\" src=\"https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-22-at-23-46-02-3-Wulzne-Csorvasi-Andrea-Facebook.png\" class=\"attachment-full size-full wp-image-603\" alt=\"\" srcset=\"https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-22-at-23-46-02-3-Wulzne-Csorvasi-Andrea-Facebook.png 190w, https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/Screenshot-2022-01-22-at-23-46-02-3-Wulzne-Csorvasi-Andrea-Facebook-150x150.png 150w\" sizes=\"auto, (max-width: 190px) 100vw, 190px\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Andrea W.Cs. <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">P\u00e1ciens<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-1830b6b elementor-invisible\" data-id=\"1830b6b\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b838bc5 elementor-widget elementor-widget-testimonial\" data-id=\"b838bc5\" data-element_type=\"widget\" data-widget_type=\"testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-testimonial-wrapper\">\n\t\t\t\t\t\t\t<div class=\"elementor-testimonial-content\">A doki seg\u00edt\u0151k\u00e9szs\u00e9ge, kedvess\u00e9ge \u00e9s t\u00fcrelme egyszer\u00fcen oszk\u00e1r dijat \u00e9rdemelne... mindenkinek aj\u00e1nlom...<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-testimonial-meta elementor-has-image elementor-testimonial-image-position-aside\">\n\t\t\t\t<div class=\"elementor-testimonial-meta-inner\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-image\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"252\" src=\"https:\/\/drvereshzoltan.hu\/wp-content\/uploads\/2022\/01\/271550289_4937646316293306_2341454043385144573_n-e1643059613801.jpg\" class=\"attachment-full size-full wp-image-981\" alt=\"\" \/>\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-details\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-name\">Hajnalka Sz. <\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-testimonial-job\">P\u00e1ciens<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f7cf8ec elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f7cf8ec\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=rVVv5kUoxME&quot;}\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-container elementor-hidden-phone\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-video-embed\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-502b87e2\" data-id=\"502b87e2\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1be3de1f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1be3de1f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-33cbf108 elementor-invisible\" data-id=\"33cbf108\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14f5adf elementor-widget elementor-widget-text-editor\" data-id=\"14f5adf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>S\u00fcrg\u0151s esetben bejelentkez\u00e9s telefonon<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-16d5f020 elementor-invisible\" data-id=\"16d5f020\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeInUp&quot;,&quot;animation_delay&quot;:100}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c968ce9 elementor-widget elementor-widget-text-editor\" data-id=\"2c968ce9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Bejelentkez\u00e9s<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-34fdc189 elementor-widget elementor-widget-heading\" data-id=\"34fdc189\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">+36-20-595-6665<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34cb97f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34cb97f7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0ae0e5d\" data-id=\"0ae0e5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Dr. Veresh Zolt\u00e1n PhD Sz\u00fcl\u00e9sz-n\u0151gy\u00f3gy\u00e1sz f\u0151orvos, endokrinol\u00f3gia \u00e9s anyagcserebetegs\u00e9gek szakorvosa, klinikai immunol\u00f3gus szakorvos &#8222;Fontosnak tartom az \u0151szintes\u00e9get \u00e9s a bizalmat orvos \u00e9s p\u00e1ciense k\u00f6z\u00f6tt. Minden megold\u00e1shoz figyelem, t\u00fcrelem \u00e9s odaad\u00e1s sz\u00fcks\u00e9ges.&#8221; Id\u0151pontfoglal\u00e1s 1982-ben sz\u00fclettem Beregsz\u00e1szban. K\u00f6z\u00e9piskolai tanulm\u00e1nyaimat a Beregsz\u00e1szi Bethlen G\u00e1bor Magyar Gimn\u00e1ziumban v\u00e9geztem. 2000-ben felv\u00e9telt nyertem a Semmelweis Egyetem \u00c1ltal\u00e1nos Orvostudom\u00e1nyi Kar\u00e1ra, ahol 2006-ban [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_mi_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"ocean_post_layout":"full-screen","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"off","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"on","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"off","ocean_display_footer_bottom":"off","ocean_custom_footer_template":"0","footnotes":""},"class_list":["post-286","page","type-page","status-publish","hentry","entry"],"_links":{"self":[{"href":"https:\/\/drvereshzoltan.hu\/hu_hu\/wp-json\/wp\/v2\/pages\/286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drvereshzoltan.hu\/hu_hu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/drvereshzoltan.hu\/hu_hu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/drvereshzoltan.hu\/hu_hu\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/drvereshzoltan.hu\/hu_hu\/wp-json\/wp\/v2\/comments?post=286"}],"version-history":[{"count":141,"href":"https:\/\/drvereshzoltan.hu\/hu_hu\/wp-json\/wp\/v2\/pages\/286\/revisions"}],"predecessor-version":[{"id":1997,"href":"https:\/\/drvereshzoltan.hu\/hu_hu\/wp-json\/wp\/v2\/pages\/286\/revisions\/1997"}],"wp:attachment":[{"href":"https:\/\/drvereshzoltan.hu\/hu_hu\/wp-json\/wp\/v2\/media?parent=286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}